{"id":21480,"date":"2025-12-22T15:02:24","date_gmt":"2025-12-22T15:02:24","guid":{"rendered":"https:\/\/dailywashingtoninsider.com\/index.php\/2025\/12\/22\/charbone-livre-son-premier-chargement-dhydrogene-propre-uhp-en-ontario\/"},"modified":"2025-12-22T15:02:24","modified_gmt":"2025-12-22T15:02:24","slug":"charbone-livre-son-premier-chargement-dhydrogene-propre-uhp-en-ontario","status":"publish","type":"post","link":"https:\/\/dailywashingtoninsider.com\/index.php\/2025\/12\/22\/charbone-livre-son-premier-chargement-dhydrogene-propre-uhp-en-ontario\/","title":{"rendered":"CHARBONE livre son premier chargement d\u2019hydrogene propre UHP en Ontario"},"content":{"rendered":"<\/p>\n<div>\n<p>(TheNewswire)<\/p>\n<div>\n<table>\n<tbody>\n<tr>\n<td colspan=\"10\" valign=\"bottom\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\"><\/td>\n<td valign=\"bottom\"><\/td>\n<td valign=\"bottom\"><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p> \u00a0 <\/p>\n<p>Brossard, Quebec, le 22 d\u00e9cembre 2025 TheNewswire &#8211; CORPORATION Charbone (TSXV: CH,OTC:CHHYF; OTCQB: CHHYF; FSE: K47) (\u00ab\u00a0Charbone\u00a0\u00bb ou la \u00ab\u00a0Soci\u00e9t\u00e9\u00a0\u00bb), un producteur et distributeur nord-am\u00e9ricain sp\u00e9cialis\u00e9 dans l&#8217;hydrog\u00e8ne propre Ultra Haute Puret\u00e9 (\u00ab\u00a0UHP\u00a0\u00bb) et les gaz industriels strat\u00e9giques, est heureuse d&#8217;annoncer la livraison r\u00e9ussie du premier chargement d&#8217;hydrog\u00e8ne propre UHP \u00e0 un distributeur ind\u00e9pendant bas\u00e9 en Ontario, marquant le d\u00e9but officiel de la g\u00e9n\u00e9ration de revenus pour sa division de production.<\/p>\n<p> <span>Premi\u00e8re livraison d&#8217;hydrog\u00e8ne propre UHP vers un client distributeur ind\u00e9pendant en Ontario<\/span> <\/p>\n<p> Dans le cadre du d\u00e9marrage commercial, Charbone annonce son <span>tout premier chargement d&#8217;hydrog\u00e8ne propre UHP produit \u00e0 Sorel-Tracy<\/span>, pour son <span>partenaire distributeur ind\u00e9pendant situ\u00e9 en Ontario<\/span>. Cette premi\u00e8re exp\u00e9dition confirme la capacit\u00e9 de la Soci\u00e9t\u00e9 \u00e0 approvisionner efficacement des march\u00e9s hors Qu\u00e9bec d\u00e8s la mise en service initiale. <\/p>\n<\/p>\n<p> Ce contrat marque le d\u00e9but d&#8217;une nouvelle phase de croissance commerciale pour Charbone, qui pr\u00e9voit \u00e9largir progressivement son r\u00e9seau de distribution et renforcer sa pr\u00e9sence dans les principaux corridors industriels de l&#8217;Est du Canada et du Midwest am\u00e9ricain. Compte tenu de l&#8217;acc\u00e8s limit\u00e9 \u00e0 un approvisionnement constant et fiable en hydrog\u00e8ne propre UHP sur le march\u00e9 nord-am\u00e9ricain et de la forte demande pour ses produits, Charbone ne divulgue pas les volumes de ses commandes ni les prix afin de pr\u00e9server sa position concurrentielle. Les revenus issus des activit\u00e9s de production, de distribution et de conseil de Charbone sont pr\u00e9sent\u00e9s trimestriellement sur une base consolid\u00e9e. <\/p>\n<p> \u00ab <span>Nous sommes extr\u00eamement fiers de livrer d\u00e8s aujourd&#8217;hui un hydrog\u00e8ne propre UHP produit localement \u00e0 nos premiers clients<\/span><span>,<\/span> \u00bb <span><span>a d\u00e9clar\u00e9<\/span><\/span> <span><span>Dave B. Gagnon, PDG de Charbone<\/span><\/span><span>. <\/span>\u00ab<span> Il s&#8217;agit d&#8217;un autre jalon majeur pour Charbone, mais \u00e9galement pour l&#8217;industrie de l&#8217;hydrog\u00e8ne propre UHP en Am\u00e9rique du Nord<\/span><span>.<\/span> \u00bb <\/p>\n<p> Pour plus d&#8217;informations sur la vision de Charbone, la configuration modulaire de ses usines et ses perspectives \u00e9conomiques, veuillez consulter le site web de la soci\u00e9t\u00e9 pour acc\u00e9der aux documents destin\u00e9s aux investisseurs, notamment la pr\u00e9sentation et la fiche d&#8217;information. Si vous ne l&#8217;avez pas encore fait, nous vous invitons \u00e9galement \u00e0 visionner le webinaire destin\u00e9 aux investisseurs, enregistr\u00e9 le 16 d\u00e9cembre 2025, en cliquant sur le lien suivant\u00a0: <span><span>https:\/\/info.rbmilestone.com\/<\/span><\/span>Charbone-webinar-dec-2025. <\/p>\n<p> \u00a0 <\/p>\n<p> <a href=\"https:\/\/investingnews.com\/charbone-livre-son-premier-chargement-d-hydrogene-propre-uhp-en-ontario\/\" target=\"_blank\"><\/a><span>\u00c0 propos de CORPORATION Charbone<\/span> <\/p>\n<p> Charbone est un d\u00e9veloppeur et producteur d&#8217;hydrog\u00e8ne propre Ultra Haute Puret\u00e9 (UHP) dot\u00e9 d&#8217;une plateforme de distribution de gaz industriels en pleine expansion. Gr\u00e2ce \u00e0 une approche modulaire, Charbone se concentre sur le d\u00e9veloppement d&#8217;un r\u00e9seau d&#8217;usines de production d&#8217;hydrog\u00e8ne propre en Am\u00e9rique du Nord et sur certains march\u00e9s \u00e0 l&#8217;\u00e9tranger, en commen\u00e7ant par son projet phare de Sorel-Tracy au Qu\u00e9bec. Le mod\u00e8le int\u00e9gr\u00e9 de l&#8217;entreprise r\u00e9duit les risques, am\u00e9liore l&#8217;\u00e9volutivit\u00e9 et permet de diversifier ses sources de revenus gr\u00e2ce \u00e0 des partenariats dans le domaine de l&#8217;h\u00e9lium et d&#8217;autres gaz de sp\u00e9cialit\u00e9s. Charbone s&#8217;engage \u00e0 soutenir la transition mondiale vers une \u00e9conomie bas carbone en fournissant des solutions d&#8217;hydrog\u00e8ne propre et de gaz de sp\u00e9cialit\u00e9s accessibles et d\u00e9centralis\u00e9es, tout en soutenant les clients industriels mal desservis en gaz et en acc\u00e9l\u00e9rant la transition vers une \u00e9nergie propre locale. Charbone est cot\u00e9 sur la <span>bourse de croissance TSX (TSXV: CH,OTC:CHHYF)<\/span>; sur les <span>march\u00e9s OTC (OTCQB: CHHYF)<\/span>; et \u00e0 la <span>Bourse de Francfort (FSE: K47)<\/span>. Pour plus d&#8217;informations, veuillez visiter <span>www.<\/span>Charbone.com. <\/p>\n<p> \u00a0 <\/p>\n<p> <span>\u00c9nonc\u00e9s prospectifs<\/span> <\/p>\n<p> <span>Le pr\u00e9sent communiqu\u00e9 de presse contient des \u00e9nonc\u00e9s qui constituent de \u00ab l&#8217;information prospective \u00bb au sens des lois canadiennes sur les valeurs mobili\u00e8res (\u00ab d\u00e9clarations prospectives \u00bb). Ces d\u00e9clarations prospectives sont souvent identifi\u00e9es par des mots tels que \u00ab a l&#8217;intention \u00bb, \u00ab anticipe \u00bb, \u00ab s&#8217;attend \u00e0 \u00bb, \u00ab croit \u00bb, \u00ab planifie \u00bb, \u00ab probable \u00bb, ou des mots similaires. Les d\u00e9clarations prospectives refl\u00e8tent les attentes, estimations ou projections respectives de la direction de Charbone concernant les r\u00e9sultats ou \u00e9v\u00e9nements futurs, sur la base des opinions, hypoth\u00e8ses et estimations consid\u00e9r\u00e9es comme raisonnables par la direction \u00e0 la date \u00e0 laquelle les d\u00e9clarations sont faites. Bien que Charbone estime que les attentes exprim\u00e9es dans les d\u00e9clarations prospectives sont raisonnables, les d\u00e9clarations prospectives comportent des risques et des incertitudes, et il ne faut pas se fier ind\u00fbment aux d\u00e9clarations prospectives, car des facteurs inconnus ou impr\u00e9visibles pourraient faire en sorte que les r\u00e9sultats r\u00e9els soient sensiblement diff\u00e9rents de ceux exprim\u00e9s dans les d\u00e9clarations prospectives. Des risques et des incertitudes li\u00e9s aux activit\u00e9s de Charbone peuvent avoir une incidence sur les d\u00e9clarations prospectives. Ces risques, incertitudes et hypoth\u00e8ses comprennent, sans s&#8217;y limiter, ceux d\u00e9crits \u00e0 la rubrique \u00ab Facteurs de risque \u00bb dans le rapport de gestion de la Soci\u00e9t\u00e9 pour la p\u00e9riode termin\u00e9e le 30 septembre 2025, qui peut \u00eatre consult\u00e9e sur SEDAR+ \u00e0 l&#8217;adresse www.sedarplus.ca; ils pourraient faire en sorte que les \u00e9v\u00e9nements ou les r\u00e9sultats r\u00e9els diff\u00e8rent sensiblement de ceux pr\u00e9vus dans les d\u00e9clarations prospectives.<\/span> <\/p>\n<p> <span>Sauf si les lois sur les valeurs mobili\u00e8res applicables l&#8217;exigent, Charbone ne s&#8217;engage pas \u00e0 mettre \u00e0 jour ni \u00e0 r\u00e9viser les d\u00e9clarations prospectives.<\/span> <\/p>\n<p> <span>Ni la Bourse de croissance TSX ni son fournisseur de services de r\u00e9glementation (tel que ce terme est d\u00e9fini dans les politiques de la Bourse de croissance TSX) n&#8217;acceptent de responsabilit\u00e9 quant \u00e0 la pertinence ou \u00e0 l&#8217;exactitude du pr\u00e9sent communiqu\u00e9. <\/span> <\/p>\n<p> <span>Pour contacter Corporation Charbone\u00a0:<\/span> <\/p>\n<p> \u00a0 <\/p>\n<\/p>\n<div>\n<table>\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<p> T\u00e9l\u00e9phone bureau: +1\u00a0450 678 7171 <\/p>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<p> Courriel:\u00a0 <span>ir@<\/span>Charbone.com <\/p>\n<p> Benoit Veilleux <\/p>\n<p> Chef de la direction financi\u00e8re et secr\u00e9taire corporatif <\/p>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>   \u00a0  <\/p>\n<p>Copyright (c) 2025 TheNewswire &#8211; All rights reserved.<\/p>\n<\/p>\n<\/div>\n<p>News Provided by TheNewsWire via QuoteMedia<\/p>\n<\/p>\n<div>This post appeared first on investingnews.com<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(TheNewswire) \u00a0 Brossard, Quebec, le 22 d\u00e9cembre 2025 TheNewswire &#8211; CORPORATION Charbone (TSXV: CH,OTC:CHHYF; OTCQB:&hellip;<\/p>\n","protected":false},"author":1,"featured_media":21481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-21480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investing"],"_links":{"self":[{"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/posts\/21480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/comments?post=21480"}],"version-history":[{"count":0,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/posts\/21480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/media\/21481"}],"wp:attachment":[{"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/media?parent=21480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/categories?post=21480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailywashingtoninsider.com\/index.php\/wp-json\/wp\/v2\/tags?post=21480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}